{"id":5754,"date":"2019-04-30T10:06:47","date_gmt":"2019-04-30T08:06:47","guid":{"rendered":"https:\/\/chupetespersonalizados.com\/?p=5754"},"modified":"2019-04-22T22:07:40","modified_gmt":"2019-04-22T20:07:40","slug":"chupetes-para-el-dia-de-la-madre","status":"publish","type":"post","link":"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/","title":{"rendered":"Chupetes para el D\u00eda de la madre"},"content":{"rendered":"\n<p>Por supuesto, nuestro regalo por excelencia siguen siendo los <a href=\"https:\/\/www.tutete.com\/tienda\/index.php?mainSearch=chupetes+dia+de+la+madre&amp;language=es\">chupetes personalizados para mam\u00e1s y abuelas<\/a>. Elige entre los dise\u00f1os que tenemos o <a href=\"https:\/\/www.tutete.com\/tienda\/es\/61_chupetes\/64_personalizados-con-dibujitos\/13084_1-chupete-personalizado-canpol-corazon-transparente.html\">personal\u00edzalo con tu propia frase<\/a> en dos o tres l\u00edneas, seg\u00fan el modelo.<\/p>\n\n\n\n<p>Mam\u00e1. Abuela. Dos <strong>palabras llenas, llenas de amor<\/strong>. Con tonos pastel y un coraz\u00f3n encima que dice <em>te quiero<\/em> de la forma m\u00e1s tierna.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"882\" height=\"344\" src=\"https:\/\/chupetespersonalizados.com\/wp-content\/uploads\/2019\/04\/chupetes-dia-de-la-madre-01.jpg\" alt=\"chupetes para mam\u00e1s\" class=\"wp-image-5762\"\/><\/figure>\n\n\n\n<p>Con un aire retro ten\u00e9is <strong>mensajes muy dulces para conquistar a mam\u00e1s y abuelas<\/strong>, en diferentes lenguas.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"882\" height=\"588\" src=\"https:\/\/chupetespersonalizados.com\/wp-content\/uploads\/2019\/04\/chupetes-dia-de-la-madre-02.jpg\" alt=\"chupetes para mam\u00e1s\" class=\"wp-image-5763\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"882\" height=\"588\" src=\"https:\/\/chupetespersonalizados.com\/wp-content\/uploads\/2019\/04\/chupetes-dia-de-la-madre-03.jpg\" alt=\"\" class=\"wp-image-5764\"\/><\/figure>\n\n\n\n<p>El chupete Tutete Classic es exclusivo de Tutete y puedes configurarlo de muchas maneras, eligiendo frases en diferentes idiomas y muchos colores, adem\u00e1s de la tetina m\u00e1s adecuada para tu beb\u00e9. <\/p>\n\n\n\n<p>Las tetinas son a elegir entre silicona y l\u00e1tex, con forma anat\u00f3mica y fisiol\u00f3gica.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"882\" height=\"428\" src=\"https:\/\/chupetespersonalizados.com\/wp-content\/uploads\/2019\/04\/chupetes-dia-de-la-madre-05.jpg\" alt=\"\" class=\"wp-image-5765\"\/><\/figure>\n\n\n\n<p>La anilla y la base del chupete son de trit\u00e1n y el bot\u00f3n central donde va la frase es de polipropileno. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"882\" height=\"588\" src=\"https:\/\/chupetespersonalizados.com\/wp-content\/uploads\/2019\/04\/chupetes-dia-de-la-madre-06.jpg\" alt=\"\" class=\"wp-image-5767\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"882\" height=\"378\" src=\"https:\/\/chupetespersonalizados.com\/wp-content\/uploads\/2019\/04\/chupetes-dia-de-la-madre-04.jpg\" alt=\"\" class=\"wp-image-5766\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"882\" height=\"345\" src=\"https:\/\/chupetespersonalizados.com\/wp-content\/uploads\/2019\/04\/chupetes-dia-de-la-madre-07.jpg\" alt=\"\" class=\"wp-image-5768\"\/><\/figure>\n\n\n\n<p>Pod\u00e9is a\u00f1adirle capucha tambi\u00e9n si la quer\u00e9is, <a href=\"https:\/\/www.tutete.com\/tienda\/product_info.php?cPath=61&amp;products_id=631\">aqu\u00ed<\/a>.<\/p>\n\n\n\n<p>Estos chupetes son un regalo muy tierno para mam\u00e1s y abuelas, y a\u00fan est\u00e1s a tiempo de que lleguen para el D\u00eda de la Madre. Confirma los plazos al hacer el pedido, por si acaso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por supuesto, nuestro regalo por excelencia siguen siendo los chupetes personalizados para mam\u00e1s y abuelas. Elige entre los dise\u00f1os que tenemos o personal\u00edzalo con tu propia frase en dos o tres l\u00edneas, seg\u00fan el modelo. Mam\u00e1. Abuela. Dos palabras llenas, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tutete-com"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chupetes para el D\u00eda de la madre - Chupetes Personalizados - El blog de Tutete<\/title>\n<meta name=\"description\" content=\"Por supuesto, nuestro regalo por excelencia siguen siendo los chupetes personalizados para mam\u00e1s y abuelas. Elige entre los dise\u00f1os que tenemos o\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chupetes para el D\u00eda de la madre - Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"og:description\" content=\"Por supuesto, nuestro regalo por excelencia siguen siendo los chupetes personalizados para mam\u00e1s y abuelas. Elige entre los dise\u00f1os que tenemos o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/\" \/>\n<meta property=\"og:site_name\" content=\"Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tutetecom\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/tutetecom\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-30T08:06:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/04\/chupetes-dia-de-la-madre-06.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"882\" \/>\n\t<meta property=\"og:image:height\" content=\"588\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Teresa Olivares\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:site\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Teresa Olivares\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/\"},\"author\":{\"name\":\"Teresa Olivares\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276\"},\"headline\":\"Chupetes para el D\u00eda de la madre\",\"datePublished\":\"2019-04-30T08:06:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/\"},\"wordCount\":217,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/04\/chupetes-dia-de-la-madre-06.jpg\",\"articleSection\":[\"Tutete.com\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/\",\"url\":\"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/\",\"name\":\"Chupetes para el D\u00eda de la madre - Chupetes Personalizados - El blog de Tutete\",\"isPartOf\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/04\/chupetes-dia-de-la-madre-06.jpg\",\"datePublished\":\"2019-04-30T08:06:47+00:00\",\"author\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276\"},\"description\":\"Por supuesto, nuestro regalo por excelencia siguen siendo los chupetes personalizados para mam\u00e1s y abuelas. Elige entre los dise\u00f1os que tenemos o\",\"breadcrumb\":{\"@id\":\"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/#primaryimage\",\"url\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/04\/chupetes-dia-de-la-madre-06.jpg\",\"contentUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/04\/chupetes-dia-de-la-madre-06.jpg\",\"width\":882,\"height\":588},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.tutete.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutete.com\",\"item\":\"https:\/\/www.tutete.com\/blog\/tutete-com\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chupetes para el D\u00eda de la madre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\",\"url\":\"https:\/\/www.tutete.com\/blog\/\",\"name\":\"Chupetes Personalizados - El blog de Tutete\",\"description\":\"Chupetes Personalizados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tutete.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276\",\"name\":\"Teresa Olivares\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/31d42492817d98c90e23b617c69d9c180bda5e793eab7ccce300f9d07332f771?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/31d42492817d98c90e23b617c69d9c180bda5e793eab7ccce300f9d07332f771?s=96&d=mm&r=g\",\"caption\":\"Teresa Olivares\"},\"description\":\"Soy Teresa Olivares, cofundadora y CEO de Tutete, una marca que naci\u00f3 en 2007 para dar respuesta a una necesidad real en escuelas infantiles: identificar los chupetes de forma higi\u00e9nica y duradera. En Tutete comparto la visi\u00f3n detr\u00e1s de la marca, as\u00ed como ideas y reflexiones sobre los productos m\u00e1s punteros del sector infantil.\",\"sameAs\":[\"https:\/\/www.tutete.com\/\",\"https:\/\/www.facebook.com\/tutetecom\",\"https:\/\/www.linkedin.com\/in\/teresa-o-7828b34b\/\",\"https:\/\/www.youtube.com\/user\/TuteteSpain\"],\"url\":\"https:\/\/tutete.com\/blog\/author\/teresa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chupetes para el D\u00eda de la madre - Chupetes Personalizados - El blog de Tutete","description":"Por supuesto, nuestro regalo por excelencia siguen siendo los chupetes personalizados para mam\u00e1s y abuelas. Elige entre los dise\u00f1os que tenemos o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/","og_locale":"es_ES","og_type":"article","og_title":"Chupetes para el D\u00eda de la madre - Chupetes Personalizados - El blog de Tutete","og_description":"Por supuesto, nuestro regalo por excelencia siguen siendo los chupetes personalizados para mam\u00e1s y abuelas. Elige entre los dise\u00f1os que tenemos o","og_url":"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/","og_site_name":"Chupetes Personalizados - El blog de Tutete","article_publisher":"https:\/\/www.facebook.com\/tutetecom\/","article_author":"https:\/\/www.facebook.com\/tutetecom","article_published_time":"2019-04-30T08:06:47+00:00","og_image":[{"width":882,"height":588,"url":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/04\/chupetes-dia-de-la-madre-06.jpg","type":"image\/jpeg"}],"author":"Teresa Olivares","twitter_card":"summary_large_image","twitter_creator":"@Tutetecom","twitter_site":"@Tutetecom","twitter_misc":{"Written by":"Teresa Olivares","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/#article","isPartOf":{"@id":"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/"},"author":{"name":"Teresa Olivares","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276"},"headline":"Chupetes para el D\u00eda de la madre","datePublished":"2019-04-30T08:06:47+00:00","mainEntityOfPage":{"@id":"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/"},"wordCount":217,"commentCount":0,"image":{"@id":"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/#primaryimage"},"thumbnailUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/04\/chupetes-dia-de-la-madre-06.jpg","articleSection":["Tutete.com"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/","url":"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/","name":"Chupetes para el D\u00eda de la madre - Chupetes Personalizados - El blog de Tutete","isPartOf":{"@id":"https:\/\/www.tutete.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/#primaryimage"},"image":{"@id":"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/#primaryimage"},"thumbnailUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/04\/chupetes-dia-de-la-madre-06.jpg","datePublished":"2019-04-30T08:06:47+00:00","author":{"@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276"},"description":"Por supuesto, nuestro regalo por excelencia siguen siendo los chupetes personalizados para mam\u00e1s y abuelas. Elige entre los dise\u00f1os que tenemos o","breadcrumb":{"@id":"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/#primaryimage","url":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/04\/chupetes-dia-de-la-madre-06.jpg","contentUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/04\/chupetes-dia-de-la-madre-06.jpg","width":882,"height":588},{"@type":"BreadcrumbList","@id":"https:\/\/tutete.com\/blog\/2019\/04\/chupetes-para-el-dia-de-la-madre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.tutete.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Tutete.com","item":"https:\/\/www.tutete.com\/blog\/tutete-com\/"},{"@type":"ListItem","position":3,"name":"Chupetes para el D\u00eda de la madre"}]},{"@type":"WebSite","@id":"https:\/\/www.tutete.com\/blog\/#website","url":"https:\/\/www.tutete.com\/blog\/","name":"Chupetes Personalizados - El blog de Tutete","description":"Chupetes Personalizados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tutete.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276","name":"Teresa Olivares","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/31d42492817d98c90e23b617c69d9c180bda5e793eab7ccce300f9d07332f771?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/31d42492817d98c90e23b617c69d9c180bda5e793eab7ccce300f9d07332f771?s=96&d=mm&r=g","caption":"Teresa Olivares"},"description":"Soy Teresa Olivares, cofundadora y CEO de Tutete, una marca que naci\u00f3 en 2007 para dar respuesta a una necesidad real en escuelas infantiles: identificar los chupetes de forma higi\u00e9nica y duradera. En Tutete comparto la visi\u00f3n detr\u00e1s de la marca, as\u00ed como ideas y reflexiones sobre los productos m\u00e1s punteros del sector infantil.","sameAs":["https:\/\/www.tutete.com\/","https:\/\/www.facebook.com\/tutetecom","https:\/\/www.linkedin.com\/in\/teresa-o-7828b34b\/","https:\/\/www.youtube.com\/user\/TuteteSpain"],"url":"https:\/\/tutete.com\/blog\/author\/teresa\/"}]}},"_links":{"self":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/5754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/comments?post=5754"}],"version-history":[{"count":0,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/5754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/media\/5767"}],"wp:attachment":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/media?parent=5754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/categories?post=5754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/tags?post=5754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}