{"id":5675,"date":"2019-03-15T19:53:10","date_gmt":"2019-03-15T17:53:10","guid":{"rendered":"https:\/\/chupetespersonalizados.com\/?p=5675"},"modified":"2019-03-21T20:19:01","modified_gmt":"2019-03-21T18:19:01","slug":"baby-shower-mantas-y-arrullos-de-cuento","status":"publish","type":"post","link":"https:\/\/tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/","title":{"rendered":"Baby shower, mantas y arrullos de cuento"},"content":{"rendered":"\n<p>Baby shower es una de esas marcas que agradeces conocer cuando nace un beb\u00e9. Y es que ya sea para que lo uses en casa como para regalo las mantas y arrullos de Baby Shower son una delicia.<\/p>\n\n\n\n<p>Baby Shower es una <strong>marca de complementos de beb\u00e9 y decoraci\u00f3n que crea productos de canastilla para reci\u00e9n nacidos<\/strong> (de 0 a 5 meses) con uno de los dise\u00f1os y tejidos m\u00e1s exclusivos del mercado.<\/p>\n\n\n\n<p>Pero si solo de verlo ya dan ganas de abrazarlos \u00a1incluso sin beb\u00e9 dentro! <\/p>\n\n\n\n<p>Est\u00e1n confeccionados en Espa\u00f1a e ideados para asegurarse que los beb\u00e9s vayan bien abrigaditos.<\/p>\n\n\n\n<p>Sus saquitos cuentan con exterior en algod\u00f3n estampado e interior en tejido polar ultra-suave. <strong>Un relleno acolchado de 200g super ligero y que ayuda a mantener la temperatura del beb\u00e9<\/strong>. (<a href=\"https:\/\/www.tutete.com\/tienda\/es\/tag\/sacos-baby-shower\">https:\/\/www.tutete.com\/tienda\/es\/tag\/sacos-baby-shower<\/a>)<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"882\" height=\"588\" src=\"https:\/\/chupetespersonalizados.com\/wp-content\/uploads\/2019\/03\/baby-shower-2.jpg\" alt=\"baby shower mantas y arrullos\" class=\"wp-image-5678\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Baby shower, mantas y arrullos de cuento.<\/h2>\n\n\n\n<p>Como ves el dise\u00f1o es muy actual y dulce. Colores pastel y estampados sencillos har\u00e1n que se adapten a todos los estilos y gustos.<\/p>\n\n\n\n<p>Adem\u00e1s est\u00e1n llenos de detalles. Como los del modelo \u00abosito\u00bb, la versi\u00f3n m\u00e1s suave y calentita de la marca.<\/p>\n\n\n\n<p>Se cierra mediante unos lacitos de lino laterales perfectamente asegurados. La parte inferior del saco se puede abrir con cremallera para que puedas introducir al beb\u00e9 m\u00e1s c\u00f3modamente y si quieres abrirlo de todo tambi\u00e9n puedes.<\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"882\" height=\"588\" src=\"https:\/\/chupetespersonalizados.com\/wp-content\/uploads\/2019\/03\/baby-shower.jpg\" alt=\"baby shower mantas y arrullos\" data-id=\"5677\" data-link=\"https:\/\/chupetespersonalizados.com\/?attachment_id=5677\" class=\"wp-image-5677\"\/><\/figure><\/li><\/ul>\n\n\n\n<p>Algunas caracter\u00edsticas y recomendaciones para los saquitos y arrullos de Baby Shower<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Medidas: \u00a078 x 40 cm. <\/li><li>Recomendados de 0 a 5 meses.<\/li><li>Lavar como m\u00e1ximo a 30 grados.<\/li><li>No usar secadora<\/li><li>Planchar a baja temperatura.<\/li><li><\/li><\/ul>\n\n\n\n<p>\u00bfVerdad que son preciosos? \u00a1Nos encanta Baby Shower!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Baby shower es una de esas marcas que agradeces conocer cuando nace un beb\u00e9. Y es que ya sea para que lo uses en casa como para regalo las mantas y arrullos de Baby Shower son una delicia. Baby Shower [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5680,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tutete-com"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Baby shower, mantas y arrullos de cuento - Chupetes Personalizados - El blog de Tutete<\/title>\n<meta name=\"description\" content=\"Baby shower es una de esas marcas que agradeces conocer cuando nace un beb\u00e9. Y es que ya sea para que lo uses en casa como para regalo las mantas y\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baby shower, mantas y arrullos de cuento - Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"og:description\" content=\"Baby shower es una de esas marcas que agradeces conocer cuando nace un beb\u00e9. Y es que ya sea para que lo uses en casa como para regalo las mantas y\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/\" \/>\n<meta property=\"og:site_name\" content=\"Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tutetecom\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/tutetecom\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-15T17:53:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-21T18:19:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tutete.com\/blog\/wp-content\/uploads\/2019\/03\/baby-shower-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"882\" \/>\n\t<meta property=\"og:image:height\" content=\"588\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Teresa Olivares\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:site\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Teresa Olivares\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/\"},\"author\":{\"name\":\"Teresa Olivares\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276\"},\"headline\":\"Baby shower, mantas y arrullos de cuento\",\"datePublished\":\"2019-03-15T17:53:10+00:00\",\"dateModified\":\"2019-03-21T18:19:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/\"},\"wordCount\":288,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/03\/baby-shower-4.jpg\",\"articleSection\":[\"Tutete.com\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/\",\"url\":\"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/\",\"name\":\"Baby shower, mantas y arrullos de cuento - Chupetes Personalizados - El blog de Tutete\",\"isPartOf\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/03\/baby-shower-4.jpg\",\"datePublished\":\"2019-03-15T17:53:10+00:00\",\"dateModified\":\"2019-03-21T18:19:01+00:00\",\"author\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276\"},\"description\":\"Baby shower es una de esas marcas que agradeces conocer cuando nace un beb\u00e9. Y es que ya sea para que lo uses en casa como para regalo las mantas y\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/#primaryimage\",\"url\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/03\/baby-shower-4.jpg\",\"contentUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/03\/baby-shower-4.jpg\",\"width\":882,\"height\":588,\"caption\":\"baby shower mantas y arrullos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.tutete.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutete.com\",\"item\":\"https:\/\/www.tutete.com\/blog\/tutete-com\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Baby shower, mantas y arrullos de cuento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\",\"url\":\"https:\/\/www.tutete.com\/blog\/\",\"name\":\"Chupetes Personalizados - El blog de Tutete\",\"description\":\"Chupetes Personalizados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tutete.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276\",\"name\":\"Teresa Olivares\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/31d42492817d98c90e23b617c69d9c180bda5e793eab7ccce300f9d07332f771?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/31d42492817d98c90e23b617c69d9c180bda5e793eab7ccce300f9d07332f771?s=96&d=mm&r=g\",\"caption\":\"Teresa Olivares\"},\"description\":\"Soy Teresa Olivares, cofundadora y CEO de Tutete, una marca que naci\u00f3 en 2007 para dar respuesta a una necesidad real en escuelas infantiles: identificar los chupetes de forma higi\u00e9nica y duradera. En Tutete comparto la visi\u00f3n detr\u00e1s de la marca, as\u00ed como ideas y reflexiones sobre los productos m\u00e1s punteros del sector infantil.\",\"sameAs\":[\"https:\/\/www.tutete.com\/\",\"https:\/\/www.facebook.com\/tutetecom\",\"https:\/\/www.linkedin.com\/in\/teresa-o-7828b34b\/\",\"https:\/\/www.youtube.com\/user\/TuteteSpain\"],\"url\":\"https:\/\/tutete.com\/blog\/author\/teresa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Baby shower, mantas y arrullos de cuento - Chupetes Personalizados - El blog de Tutete","description":"Baby shower es una de esas marcas que agradeces conocer cuando nace un beb\u00e9. Y es que ya sea para que lo uses en casa como para regalo las mantas y","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/","og_locale":"es_ES","og_type":"article","og_title":"Baby shower, mantas y arrullos de cuento - Chupetes Personalizados - El blog de Tutete","og_description":"Baby shower es una de esas marcas que agradeces conocer cuando nace un beb\u00e9. Y es que ya sea para que lo uses en casa como para regalo las mantas y","og_url":"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/","og_site_name":"Chupetes Personalizados - El blog de Tutete","article_publisher":"https:\/\/www.facebook.com\/tutetecom\/","article_author":"https:\/\/www.facebook.com\/tutetecom","article_published_time":"2019-03-15T17:53:10+00:00","article_modified_time":"2019-03-21T18:19:01+00:00","og_image":[{"width":882,"height":588,"url":"https:\/\/www.tutete.com\/blog\/wp-content\/uploads\/2019\/03\/baby-shower-4.jpg","type":"image\/jpeg"}],"author":"Teresa Olivares","twitter_card":"summary_large_image","twitter_creator":"@Tutetecom","twitter_site":"@Tutetecom","twitter_misc":{"Written by":"Teresa Olivares","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/#article","isPartOf":{"@id":"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/"},"author":{"name":"Teresa Olivares","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276"},"headline":"Baby shower, mantas y arrullos de cuento","datePublished":"2019-03-15T17:53:10+00:00","dateModified":"2019-03-21T18:19:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/"},"wordCount":288,"commentCount":0,"image":{"@id":"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/#primaryimage"},"thumbnailUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/03\/baby-shower-4.jpg","articleSection":["Tutete.com"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/","url":"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/","name":"Baby shower, mantas y arrullos de cuento - Chupetes Personalizados - El blog de Tutete","isPartOf":{"@id":"https:\/\/www.tutete.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/#primaryimage"},"image":{"@id":"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/#primaryimage"},"thumbnailUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/03\/baby-shower-4.jpg","datePublished":"2019-03-15T17:53:10+00:00","dateModified":"2019-03-21T18:19:01+00:00","author":{"@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276"},"description":"Baby shower es una de esas marcas que agradeces conocer cuando nace un beb\u00e9. Y es que ya sea para que lo uses en casa como para regalo las mantas y","breadcrumb":{"@id":"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/#primaryimage","url":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/03\/baby-shower-4.jpg","contentUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/03\/baby-shower-4.jpg","width":882,"height":588,"caption":"baby shower mantas y arrullos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tutete.com\/blog\/2019\/03\/baby-shower-mantas-y-arrullos-de-cuento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.tutete.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Tutete.com","item":"https:\/\/www.tutete.com\/blog\/tutete-com\/"},{"@type":"ListItem","position":3,"name":"Baby shower, mantas y arrullos de cuento"}]},{"@type":"WebSite","@id":"https:\/\/www.tutete.com\/blog\/#website","url":"https:\/\/www.tutete.com\/blog\/","name":"Chupetes Personalizados - El blog de Tutete","description":"Chupetes Personalizados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tutete.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276","name":"Teresa Olivares","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/31d42492817d98c90e23b617c69d9c180bda5e793eab7ccce300f9d07332f771?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/31d42492817d98c90e23b617c69d9c180bda5e793eab7ccce300f9d07332f771?s=96&d=mm&r=g","caption":"Teresa Olivares"},"description":"Soy Teresa Olivares, cofundadora y CEO de Tutete, una marca que naci\u00f3 en 2007 para dar respuesta a una necesidad real en escuelas infantiles: identificar los chupetes de forma higi\u00e9nica y duradera. En Tutete comparto la visi\u00f3n detr\u00e1s de la marca, as\u00ed como ideas y reflexiones sobre los productos m\u00e1s punteros del sector infantil.","sameAs":["https:\/\/www.tutete.com\/","https:\/\/www.facebook.com\/tutetecom","https:\/\/www.linkedin.com\/in\/teresa-o-7828b34b\/","https:\/\/www.youtube.com\/user\/TuteteSpain"],"url":"https:\/\/tutete.com\/blog\/author\/teresa\/"}]}},"_links":{"self":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/5675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/comments?post=5675"}],"version-history":[{"count":0,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/5675\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/media\/5680"}],"wp:attachment":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/media?parent=5675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/categories?post=5675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/tags?post=5675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}