{"id":5625,"date":"2019-02-15T10:40:43","date_gmt":"2019-02-15T08:40:43","guid":{"rendered":"https:\/\/chupetespersonalizados.com\/?p=5625"},"modified":"2019-02-16T10:41:30","modified_gmt":"2019-02-16T08:41:30","slug":"leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos","status":"publish","type":"post","link":"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/","title":{"rendered":"Abuelos al borde de un ataque de nietos"},"content":{"rendered":"\n<p><br><\/p>\n\n\n\n<p>Y es el tema que aborda Leopoldo Abad\u00eda en su libro <em><a href=\"https:\/\/www.tutete.com\/tienda\/es\/96_juguetes--libros\/223_libros\/27984_abuelos-al-borde-de-un-ataque-de-nietos.html\"><strong>Abuelos al borde de un ataque de nietos<\/strong><\/a><\/em>, una obra m\u00e1s familiar y reivindicativa que las anteriores pero con el mismo humor que le caracteriza.<\/p>\n\n\n\n<p>Abuelos y abuelas, \u00a1suerte que les tenemos! M\u00e1s de una vez nos sacan de un apuro cuando el ni\u00f1o se pone malo o no llegamos a recoger a la ni\u00f1a a la salida del cole, \u00bfverdad? <br><\/p>\n\n\n\n<p>La conciliaci\u00f3n laboral y familiar tambi\u00e9n <strong>es cosa de abuelos y abuelas, ya que son quienes la hacen posible<\/strong> al atender necesidades de guarder\u00eda casi en r\u00e9gimen 24 horas. Esto es una realidad.<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Abuelos al borde de un ataque de nietos<\/strong><br><\/p>\n\n\n\n<p>Abuelos y abuelas se convierten en asistentes 24 horas pero \u00bfes esto justo para ellos? Al fin y al cabo igual no pueden \u2013o no quieren\u2013 asumir esa responsabilidad pero, claro, s\u00ed quieren echar una mano a sus hijos\u2026 Ah\u00ed la trampa que desvela Leopoldo Abad\u00eda.<\/p>\n\n\n\n<p>Ya no tienen la vitalidad \u2013ni a veces la salud\u2013 necesaria para correr detr\u00e1s de los nietos ni para aguantar los tiras y aflojas del d\u00eda a d\u00eda que acaban con la estabilidad mental de cualquiera. Y <strong>f\u00edsicamente tambi\u00e9n se notan los a\u00f1os<\/strong> y es posible que cuando se marchen los nietos y se sienten en el sof\u00e1 les duela hasta el \u00faltimo de sus huesos&#8230;<br><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"882\" height=\"588\" src=\"https:\/\/chupetespersonalizados.com\/wp-content\/uploads\/2019\/02\/leopoldo-abadia-02.jpg\" alt=\"leopoldo abadia\" class=\"wp-image-5630\"\/><\/figure>\n\n\n\n<p>Obviamente no hay una receta \u00fanica ni m\u00e1gica, y la realidad es compleja, bien lo sabemos. <strong>Abad\u00eda ofrece una reflexi\u00f3n sobre esta situaci\u00f3n real que se da en todas las familias y que deber\u00eda partir del agradecimiento hacia las figuras de los abuelos y abuelas<\/strong> y su generosa disponibilidad.<br><\/p>\n\n\n\n<p>La relaci\u00f3n entre abuelas\/-os y nietos\/-as no es la misma que la que se tiene con los padres y madres, y <strong>su cuidado no necesariamente implica educarles<\/strong> del mismo modo que hacen los progenitores. <br><\/p>\n\n\n\n<p>La flexibilidad y la cesi\u00f3n ante el capricho es parte de su funci\u00f3n tradicional, <strong>el papel de los abuelos: <\/strong><em><strong>malcriar<\/strong><\/em><strong>, en el mejor sentido del t\u00e9rmino<\/strong>. Madres y padres deben olvidarse de \u201cprolongar su f\u00e9rrea mano una vez que entregan los hijos a los abuelos\u201d. Confianza y agradecimiento.<\/p>\n\n\n\n<p>Abad\u00eda pretende, en 200 p\u00e1ginas, tratar con humor un tema complicado y que sirva para \u201caprender a disfrutar de la familia y ense\u00f1arle al lector a llevar una convivencia mucho m\u00e1s llevadera\u201d.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Sobre el autor<\/strong><br><\/p>\n\n\n\n<p>Abuelo de 48 nietos, Leopoldo Abad\u00eda no habla solo desde la teor\u00eda. Con conocimiento de causa <strong>reflexiona, con su habitual sensatez y sentido del humor, sobre los temas cotidianos de la vida<\/strong>. En este caso concreto, c\u00f3mo superar la brecha generacional que le separa de sus nietos y las diferencias con la paternidad.<br><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"882\" height=\"588\" src=\"https:\/\/chupetespersonalizados.com\/wp-content\/uploads\/2019\/02\/leopoldo-abadia-01.jpg\" alt=\"leopoldo abadia\" class=\"wp-image-5629\"\/><\/figure>\n\n\n\n<p>Probablemente, es m\u00e1s conocido por su faceta de economista, y a\u00fan le recordaremos por su libro <em>La crisis ninja<\/em>, donde explicaba de forma inteligible la crisis econ\u00f3mica mundial. A partir de ese momento, comenzamos a verle con frecuencia en televisi\u00f3n.<\/p>\n\n\n\n<p>En el fondo, <strong>este tema no est\u00e1 desligado de la econom\u00eda<\/strong> y, al humanizarla en estas personitas, nos identificamos y nos resulta mucho m\u00e1s cercano, \u00bfverdad?<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Y es el tema que aborda Leopoldo Abad\u00eda en su libro Abuelos al borde de un ataque de nietos, una obra m\u00e1s familiar y reivindicativa que las anteriores pero con el mismo humor que le caracteriza. Abuelos y abuelas, \u00a1suerte [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5628,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tutete-com"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abuelos al borde de un ataque de nietos - Chupetes Personalizados - El blog de Tutete<\/title>\n<meta name=\"description\" content=\"Y es el tema que aborda Leopoldo Abad\u00eda en su libro Abuelos al borde de un ataque de nietos, una obra m\u00e1s familiar y reivindicativa que las anteriores Leopoldo Abad\u00eda reflexi % ona en este libro sobre una realidad cotidiana que es la carga que puede suponer a cierta edad el cuidado de los nietos, con el humor y la sensatez que le caracterizan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abuelos al borde de un ataque de nietos - Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"og:description\" content=\"Y es el tema que aborda Leopoldo Abad\u00eda en su libro Abuelos al borde de un ataque de nietos, una obra m\u00e1s familiar y reivindicativa que las anteriores Leopoldo Abad\u00eda reflexi % ona en este libro sobre una realidad cotidiana que es la carga que puede suponer a cierta edad el cuidado de los nietos, con el humor y la sensatez que le caracterizan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/\" \/>\n<meta property=\"og:site_name\" content=\"Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tutetecom\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/tutetecom\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-15T08:40:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-16T08:41:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/02\/leopoldo-abadia-00.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"882\" \/>\n\t<meta property=\"og:image:height\" content=\"588\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Teresa Olivares\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:site\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Teresa Olivares\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/\"},\"author\":{\"name\":\"Teresa Olivares\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276\"},\"headline\":\"Abuelos al borde de un ataque de nietos\",\"datePublished\":\"2019-02-15T08:40:43+00:00\",\"dateModified\":\"2019-02-16T08:41:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/\"},\"wordCount\":555,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/02\/leopoldo-abadia-00.jpg\",\"articleSection\":[\"Tutete.com\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/\",\"url\":\"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/\",\"name\":\"Abuelos al borde de un ataque de nietos - Chupetes Personalizados - El blog de Tutete\",\"isPartOf\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/02\/leopoldo-abadia-00.jpg\",\"datePublished\":\"2019-02-15T08:40:43+00:00\",\"dateModified\":\"2019-02-16T08:41:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276\"},\"description\":\"Y es el tema que aborda Leopoldo Abad\u00eda en su libro Abuelos al borde de un ataque de nietos, una obra m\u00e1s familiar y reivindicativa que las anteriores Leopoldo Abad\u00eda reflexi % ona en este libro sobre una realidad cotidiana que es la carga que puede suponer a cierta edad el cuidado de los nietos, con el humor y la sensatez que le caracterizan.\",\"breadcrumb\":{\"@id\":\"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/#primaryimage\",\"url\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/02\/leopoldo-abadia-00.jpg\",\"contentUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/02\/leopoldo-abadia-00.jpg\",\"width\":882,\"height\":588,\"caption\":\"leopoldo abadia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.tutete.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutete.com\",\"item\":\"https:\/\/www.tutete.com\/blog\/tutete-com\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Abuelos al borde de un ataque de nietos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\",\"url\":\"https:\/\/www.tutete.com\/blog\/\",\"name\":\"Chupetes Personalizados - El blog de Tutete\",\"description\":\"Chupetes Personalizados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tutete.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276\",\"name\":\"Teresa Olivares\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/31d42492817d98c90e23b617c69d9c180bda5e793eab7ccce300f9d07332f771?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/31d42492817d98c90e23b617c69d9c180bda5e793eab7ccce300f9d07332f771?s=96&d=mm&r=g\",\"caption\":\"Teresa Olivares\"},\"description\":\"Soy Teresa Olivares, cofundadora y CEO de Tutete, una marca que naci\u00f3 en 2007 para dar respuesta a una necesidad real en escuelas infantiles: identificar los chupetes de forma higi\u00e9nica y duradera. En Tutete comparto la visi\u00f3n detr\u00e1s de la marca, as\u00ed como ideas y reflexiones sobre los productos m\u00e1s punteros del sector infantil.\",\"sameAs\":[\"https:\/\/www.tutete.com\/\",\"https:\/\/www.facebook.com\/tutetecom\",\"https:\/\/www.linkedin.com\/in\/teresa-o-7828b34b\/\",\"https:\/\/www.youtube.com\/user\/TuteteSpain\"],\"url\":\"https:\/\/tutete.com\/blog\/author\/teresa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abuelos al borde de un ataque de nietos - Chupetes Personalizados - El blog de Tutete","description":"Y es el tema que aborda Leopoldo Abad\u00eda en su libro Abuelos al borde de un ataque de nietos, una obra m\u00e1s familiar y reivindicativa que las anteriores Leopoldo Abad\u00eda reflexi % ona en este libro sobre una realidad cotidiana que es la carga que puede suponer a cierta edad el cuidado de los nietos, con el humor y la sensatez que le caracterizan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/","og_locale":"es_ES","og_type":"article","og_title":"Abuelos al borde de un ataque de nietos - Chupetes Personalizados - El blog de Tutete","og_description":"Y es el tema que aborda Leopoldo Abad\u00eda en su libro Abuelos al borde de un ataque de nietos, una obra m\u00e1s familiar y reivindicativa que las anteriores Leopoldo Abad\u00eda reflexi % ona en este libro sobre una realidad cotidiana que es la carga que puede suponer a cierta edad el cuidado de los nietos, con el humor y la sensatez que le caracterizan.","og_url":"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/","og_site_name":"Chupetes Personalizados - El blog de Tutete","article_publisher":"https:\/\/www.facebook.com\/tutetecom\/","article_author":"https:\/\/www.facebook.com\/tutetecom","article_published_time":"2019-02-15T08:40:43+00:00","article_modified_time":"2019-02-16T08:41:30+00:00","og_image":[{"width":882,"height":588,"url":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/02\/leopoldo-abadia-00.jpg","type":"image\/jpeg"}],"author":"Teresa Olivares","twitter_card":"summary_large_image","twitter_creator":"@Tutetecom","twitter_site":"@Tutetecom","twitter_misc":{"Written by":"Teresa Olivares","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/#article","isPartOf":{"@id":"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/"},"author":{"name":"Teresa Olivares","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276"},"headline":"Abuelos al borde de un ataque de nietos","datePublished":"2019-02-15T08:40:43+00:00","dateModified":"2019-02-16T08:41:30+00:00","mainEntityOfPage":{"@id":"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/"},"wordCount":555,"commentCount":0,"image":{"@id":"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/#primaryimage"},"thumbnailUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/02\/leopoldo-abadia-00.jpg","articleSection":["Tutete.com"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/","url":"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/","name":"Abuelos al borde de un ataque de nietos - Chupetes Personalizados - El blog de Tutete","isPartOf":{"@id":"https:\/\/www.tutete.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/#primaryimage"},"image":{"@id":"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/#primaryimage"},"thumbnailUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/02\/leopoldo-abadia-00.jpg","datePublished":"2019-02-15T08:40:43+00:00","dateModified":"2019-02-16T08:41:30+00:00","author":{"@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276"},"description":"Y es el tema que aborda Leopoldo Abad\u00eda en su libro Abuelos al borde de un ataque de nietos, una obra m\u00e1s familiar y reivindicativa que las anteriores Leopoldo Abad\u00eda reflexi % ona en este libro sobre una realidad cotidiana que es la carga que puede suponer a cierta edad el cuidado de los nietos, con el humor y la sensatez que le caracterizan.","breadcrumb":{"@id":"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/#primaryimage","url":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/02\/leopoldo-abadia-00.jpg","contentUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2019\/02\/leopoldo-abadia-00.jpg","width":882,"height":588,"caption":"leopoldo abadia"},{"@type":"BreadcrumbList","@id":"https:\/\/tutete.com\/blog\/2019\/02\/leopoldo-abadia-abuelos-al-borde-de-un-ataque-de-nietos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.tutete.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Tutete.com","item":"https:\/\/www.tutete.com\/blog\/tutete-com\/"},{"@type":"ListItem","position":3,"name":"Abuelos al borde de un ataque de nietos"}]},{"@type":"WebSite","@id":"https:\/\/www.tutete.com\/blog\/#website","url":"https:\/\/www.tutete.com\/blog\/","name":"Chupetes Personalizados - El blog de Tutete","description":"Chupetes Personalizados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tutete.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/f61de13dced5c4a1e5fe2c6aea8a8276","name":"Teresa Olivares","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/31d42492817d98c90e23b617c69d9c180bda5e793eab7ccce300f9d07332f771?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/31d42492817d98c90e23b617c69d9c180bda5e793eab7ccce300f9d07332f771?s=96&d=mm&r=g","caption":"Teresa Olivares"},"description":"Soy Teresa Olivares, cofundadora y CEO de Tutete, una marca que naci\u00f3 en 2007 para dar respuesta a una necesidad real en escuelas infantiles: identificar los chupetes de forma higi\u00e9nica y duradera. En Tutete comparto la visi\u00f3n detr\u00e1s de la marca, as\u00ed como ideas y reflexiones sobre los productos m\u00e1s punteros del sector infantil.","sameAs":["https:\/\/www.tutete.com\/","https:\/\/www.facebook.com\/tutetecom","https:\/\/www.linkedin.com\/in\/teresa-o-7828b34b\/","https:\/\/www.youtube.com\/user\/TuteteSpain"],"url":"https:\/\/tutete.com\/blog\/author\/teresa\/"}]}},"_links":{"self":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/5625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/comments?post=5625"}],"version-history":[{"count":0,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/5625\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/media\/5628"}],"wp:attachment":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/media?parent=5625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/categories?post=5625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/tags?post=5625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}