{"id":2740,"date":"2014-09-09T09:24:38","date_gmt":"2014-09-09T09:24:38","guid":{"rendered":"http:\/\/chupetespersonalizados.com\/?p=2740"},"modified":"2014-09-09T09:24:38","modified_gmt":"2014-09-09T09:24:38","slug":"primer-dia-guarderia","status":"publish","type":"post","link":"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/","title":{"rendered":"El primer d\u00eda de guarder\u00eda de mi beb\u00e9"},"content":{"rendered":"<p><strong>El primer d\u00eda de guarder\u00eda es un momento muy importante en la vida del beb\u00e9<\/strong>, y tambi\u00e9n en la de sus padres, que lo vivimos con gran nerviosismo e ilusi\u00f3n.<!--more--><\/p>\n<p><strong>A muchos ni\u00f1os les resulta complicado adaptarse a su nueva vida en la guarder\u00eda<\/strong>, sobretodo los primeros d\u00edas. Y es algo normal, sobretodo teniendo en cuenta que tienen que adaptarse a los nuevos horarios y rutinas, comidas, compa\u00f1eros, profesores&#8230;<\/p>\n<p><strong>En esta fase es muy importante el apoyo y cari\u00f1o de los padres<\/strong>, que debemos transmitir tranquilidad y confianza a los peques.<\/p>\n<h3>Consejos para el primer d\u00eda de guarder\u00eda del beb\u00e9<\/h3>\n<p>Como sabemos lo complicado que puede llegar a ser para todos que el beb\u00e9 se adapte a la guarde, hoy te damos estos consejitos para el primer d\u00eda de guarder\u00eda del beb\u00e9:<\/p>\n<ol>\n<li><strong>Acostumbra al beb\u00e9 a estar separados de sus pap\u00e1s<\/strong>; aunque sea durante unas horas al d\u00eda, es bueno que el beb\u00e9 se acostumbre a estar con sus abuelos, t\u00edos&#8230; para que la separaci\u00f3n el d\u00eda de la guarder\u00eda no le suponga un problema.<\/li>\n<li><strong>Visita el edificio con tu beb\u00e9 antes de dejarlo all\u00ed por primera vez<\/strong>; as\u00ed, conocer\u00e1 el lugar y no le ser\u00e1 todo tan extra\u00f1o.<\/li>\n<li><strong>Empieza con jornadas cortas<\/strong>; unas pocas horas al d\u00eda al principio, para ir aument\u00e1ndolas a medida que pase el tiempo es lo ideal para que los peques no sufran mucho.<\/li>\n<li><strong>Desp\u00eddete de forma natural<\/strong>; los beb\u00e9s pueden sentirse abandonados si les dejas all\u00ed y te vas a hurtadillas, lo mejor es explicarle que se queda all\u00ed a aprender mucho y pasarlo bien y que volver\u00e1s a buscarle luego.<\/li>\n<li><strong>No debes sucumbir a los llantos y pataletas<\/strong> del beb\u00e9, tampoco le ofrezcas premios o golosinas para que se calme; debe acostumbrarse a ir a la guarder\u00eda de forma natural.<\/li>\n<\/ol>\n<p><strong>\u00bfQu\u00e9 tal se ha adaptado tu beb\u00e9 a la guarder\u00eda?<\/strong> Si conoces alg\u00fan truquito para que su adaptaci\u00f3n sea m\u00e1s f\u00e1cil, \u00a1comp\u00e1rtelo con nosotros!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El primer d\u00eda de guarder\u00eda es un momento muy importante en la vida del beb\u00e9, y tambi\u00e9n en la de sus padres, que lo vivimos con gran nerviosismo e ilusi\u00f3n.<\/p>\n","protected":false},"author":1,"featured_media":2741,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[545],"tags":[437],"class_list":["post-2740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recomendaciones","tag-consejos-bebes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El primer d\u00eda de guarder\u00eda de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete<\/title>\n<meta name=\"description\" content=\"El primer d\u00eda de guarder\u00eda es un momento muy importante en la vida del beb\u00e9, y tambi\u00e9n en la de sus padres, que lo vivimos con gran nerviosismo e ilusi\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El primer d\u00eda de guarder\u00eda de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"og:description\" content=\"El primer d\u00eda de guarder\u00eda es un momento muy importante en la vida del beb\u00e9, y tambi\u00e9n en la de sus padres, que lo vivimos con gran nerviosismo e ilusi\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/\" \/>\n<meta property=\"og:site_name\" content=\"Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tutetecom\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-09T09:24:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/09\/bebe_guarderia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"tutete\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:site\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"tutete\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/\"},\"author\":{\"name\":\"tutete\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\"},\"headline\":\"El primer d\u00eda de guarder\u00eda de mi beb\u00e9\",\"datePublished\":\"2014-09-09T09:24:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/\"},\"wordCount\":363,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/09\/bebe_guarderia.jpg\",\"keywords\":[\"consejos beb\u00e9s\"],\"articleSection\":[\"Recomendaciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/\",\"url\":\"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/\",\"name\":\"El primer d\u00eda de guarder\u00eda de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete\",\"isPartOf\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/09\/bebe_guarderia.jpg\",\"datePublished\":\"2014-09-09T09:24:38+00:00\",\"author\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\"},\"description\":\"El primer d\u00eda de guarder\u00eda es un momento muy importante en la vida del beb\u00e9, y tambi\u00e9n en la de sus padres, que lo vivimos con gran nerviosismo e ilusi\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/#primaryimage\",\"url\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/09\/bebe_guarderia.jpg\",\"contentUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/09\/bebe_guarderia.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.tutete.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recomendaciones\",\"item\":\"https:\/\/erp-pre.tutete.com\/blog\/recomendaciones\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El primer d\u00eda de guarder\u00eda de mi beb\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\",\"url\":\"https:\/\/www.tutete.com\/blog\/\",\"name\":\"Chupetes Personalizados - El blog de Tutete\",\"description\":\"Chupetes Personalizados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tutete.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\",\"name\":\"tutete\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g\",\"caption\":\"tutete\"},\"url\":\"https:\/\/tutete.com\/blog\/author\/tutete\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El primer d\u00eda de guarder\u00eda de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete","description":"El primer d\u00eda de guarder\u00eda es un momento muy importante en la vida del beb\u00e9, y tambi\u00e9n en la de sus padres, que lo vivimos con gran nerviosismo e ilusi\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/","og_locale":"es_ES","og_type":"article","og_title":"El primer d\u00eda de guarder\u00eda de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete","og_description":"El primer d\u00eda de guarder\u00eda es un momento muy importante en la vida del beb\u00e9, y tambi\u00e9n en la de sus padres, que lo vivimos con gran nerviosismo e ilusi\u00f3n.","og_url":"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/","og_site_name":"Chupetes Personalizados - El blog de Tutete","article_publisher":"https:\/\/www.facebook.com\/tutetecom\/","article_published_time":"2014-09-09T09:24:38+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/09\/bebe_guarderia.jpg","type":"image\/jpeg"}],"author":"tutete","twitter_card":"summary_large_image","twitter_creator":"@Tutetecom","twitter_site":"@Tutetecom","twitter_misc":{"Written by":"tutete","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/#article","isPartOf":{"@id":"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/"},"author":{"name":"tutete","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf"},"headline":"El primer d\u00eda de guarder\u00eda de mi beb\u00e9","datePublished":"2014-09-09T09:24:38+00:00","mainEntityOfPage":{"@id":"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/"},"wordCount":363,"commentCount":0,"image":{"@id":"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/#primaryimage"},"thumbnailUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/09\/bebe_guarderia.jpg","keywords":["consejos beb\u00e9s"],"articleSection":["Recomendaciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/","url":"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/","name":"El primer d\u00eda de guarder\u00eda de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete","isPartOf":{"@id":"https:\/\/www.tutete.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/#primaryimage"},"image":{"@id":"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/#primaryimage"},"thumbnailUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/09\/bebe_guarderia.jpg","datePublished":"2014-09-09T09:24:38+00:00","author":{"@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf"},"description":"El primer d\u00eda de guarder\u00eda es un momento muy importante en la vida del beb\u00e9, y tambi\u00e9n en la de sus padres, que lo vivimos con gran nerviosismo e ilusi\u00f3n.","breadcrumb":{"@id":"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/#primaryimage","url":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/09\/bebe_guarderia.jpg","contentUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/09\/bebe_guarderia.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/tutete.com\/blog\/2014\/09\/primer-dia-guarderia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.tutete.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Recomendaciones","item":"https:\/\/erp-pre.tutete.com\/blog\/recomendaciones\/"},{"@type":"ListItem","position":3,"name":"El primer d\u00eda de guarder\u00eda de mi beb\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.tutete.com\/blog\/#website","url":"https:\/\/www.tutete.com\/blog\/","name":"Chupetes Personalizados - El blog de Tutete","description":"Chupetes Personalizados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tutete.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf","name":"tutete","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g","caption":"tutete"},"url":"https:\/\/tutete.com\/blog\/author\/tutete\/"}]}},"_links":{"self":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/2740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/comments?post=2740"}],"version-history":[{"count":0,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/2740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/media\/2741"}],"wp:attachment":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/media?parent=2740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/categories?post=2740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/tags?post=2740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}