{"id":2733,"date":"2014-08-28T11:59:13","date_gmt":"2014-08-28T11:59:13","guid":{"rendered":"http:\/\/chupetespersonalizados.com\/?p=2733"},"modified":"2014-08-28T11:59:13","modified_gmt":"2014-08-28T11:59:13","slug":"miedo-oscuridad","status":"publish","type":"post","link":"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/","title":{"rendered":"C\u00f3mo superar el miedo a la oscuridad"},"content":{"rendered":"<p>El miedo no es m\u00e1s que una reacci\u00f3n de protecci\u00f3n del organismo para huir de las situaciones que percibe como peligrosas.<strong> Uno de los miedos m\u00e1s comunes entre los ni\u00f1os es el miedo a la oscuridad<\/strong>.<!--more--><\/p>\n<p><strong>El miedo a la oscuridad comienza alrededor de los dos a\u00f1os<\/strong>, que es cuando el ni\u00f1o desarrolla al m\u00e1ximo su imaginaci\u00f3n, y contin\u00faa siendo frecuente hasta los nueve a\u00f1os.<\/p>\n<p><strong>Los efectos mas frecuentes del miedo a la oscuridad se manifiestan a trav\u00e9s de pesadillas y terrores nocturnos<\/strong> que producen al ni\u00f1o situaciones de inseguridad.<\/p>\n<h3>\u00bfPor qu\u00e9 los ni\u00f1os tienen miedo a la oscuridad?<\/h3>\n<ul>\n<li><strong>La imaginaci\u00f3n de los ni\u00f1os se multiplica en la oscuridad<\/strong>, lo que les hace pensar que la oscuridad esconde a personas desconocidas o monstruos debajo de su cama, dentro de su armario o detr\u00e1s de las cortinas de su habitaci\u00f3n.<\/li>\n<li><strong>En la oscuridad, no hay referencias visuales y esto hace que los ni\u00f1os no se sientan seguros<\/strong> y empiecen a imaginar la existencia de alguna presencia extra\u00f1a e imaginaria como los fantasmas, los monstruos, etc.. <\/li>\n<li>Tambi\u00e9n sucede que <strong>cuando llega la oscuridad, los padres se van y ya no pueden hacer nada divertido<\/strong>. En ese caso, no se trata de miedo y s\u00ed de inquietud por lo que ya no puede hacer.<\/li>\n<\/ul>\n<h3>C\u00f3mo superar el miedo a la oscuridad<\/h3>\n<ol>\n<li><strong>Habla de su miedo con normalidad<\/strong>; debemos hacerle saber al ni\u00f1o que tener miedo es normal; todo el mundo teme a algo, y no es algo de lo que deba avergonzarse.<\/li>\n<li><strong>Juega con \u00e9l en la oscuridad<\/strong>;  jugar en la oscuridad durante el d\u00eda, con las persianas de la habitaci\u00f3n bajadas ayuda a perder el miedo a la oscuridad como tal y familiarizarse con la ausencia de luz.<\/li>\n<li><strong>Relaja al ni\u00f1o antes de ir a dormir<\/strong>; con un cuento, una ducha, una canci\u00f3n o una m\u00fasica tranquila pueden ayudar a que se relaje. <\/li>\n<li><strong>Evita que vea pel\u00edculas y programas de televisi\u00f3n de miedo<\/strong>; que puedan asustarle y aumentar su miedo a quedarse solo en la oscuridad.<\/li>\n<li>Deja una luz muy tenue; lo ideal es que casi no ilumine pero que s\u00ed aporte algo de claridad en la habitaci\u00f3n.<\/li>\n<li><strong>No enciendas la luz cuando est\u00e9 muy asustado<\/strong>; si lo haces, aumentar\u00e1 el problema, pues ratificar\u00e1 la idea de que la oscuridad da miedo y que la luz lo quita.<\/li>\n<\/ol>\n<p>Y tu peque, <strong>\u00bftiene miedo a la oscuridad?\u00bfC\u00f3mo le ayudas t\u00fa a superarlo?<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El miedo no es m\u00e1s que una reacci\u00f3n de protecci\u00f3n del organismo para huir de las situaciones que percibe como peligrosas. Uno de los miedos m\u00e1s comunes entre los ni\u00f1os es el miedo a la oscuridad.<\/p>\n","protected":false},"author":1,"featured_media":2734,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[545],"tags":[437],"class_list":["post-2733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recomendaciones","tag-consejos-bebes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo superar el miedo a la oscuridad - Chupetes Personalizados - El blog de Tutete<\/title>\n<meta name=\"description\" content=\"El miedo no es m\u00e1s que una reacci\u00f3n de protecci\u00f3n del organismo para huir de las situaciones que percibe como peligrosas. Uno de los miedos m\u00e1s comunes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo superar el miedo a la oscuridad - Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"og:description\" content=\"El miedo no es m\u00e1s que una reacci\u00f3n de protecci\u00f3n del organismo para huir de las situaciones que percibe como peligrosas. Uno de los miedos m\u00e1s comunes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/\" \/>\n<meta property=\"og:site_name\" content=\"Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tutetecom\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-08-28T11:59:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/08\/miedo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"tutete\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:site\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"tutete\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/\"},\"author\":{\"name\":\"tutete\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\"},\"headline\":\"C\u00f3mo superar el miedo a la oscuridad\",\"datePublished\":\"2014-08-28T11:59:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/\"},\"wordCount\":440,\"commentCount\":2,\"image\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/08\/miedo.jpg\",\"keywords\":[\"consejos beb\u00e9s\"],\"articleSection\":[\"Recomendaciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/\",\"url\":\"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/\",\"name\":\"C\u00f3mo superar el miedo a la oscuridad - Chupetes Personalizados - El blog de Tutete\",\"isPartOf\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/08\/miedo.jpg\",\"datePublished\":\"2014-08-28T11:59:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\"},\"description\":\"El miedo no es m\u00e1s que una reacci\u00f3n de protecci\u00f3n del organismo para huir de las situaciones que percibe como peligrosas. Uno de los miedos m\u00e1s comunes\",\"breadcrumb\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/#primaryimage\",\"url\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/08\/miedo.jpg\",\"contentUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/08\/miedo.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.tutete.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recomendaciones\",\"item\":\"https:\/\/erp-pre.tutete.com\/blog\/recomendaciones\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo superar el miedo a la oscuridad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\",\"url\":\"https:\/\/www.tutete.com\/blog\/\",\"name\":\"Chupetes Personalizados - El blog de Tutete\",\"description\":\"Chupetes Personalizados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tutete.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\",\"name\":\"tutete\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g\",\"caption\":\"tutete\"},\"url\":\"https:\/\/tutete.com\/blog\/author\/tutete\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo superar el miedo a la oscuridad - Chupetes Personalizados - El blog de Tutete","description":"El miedo no es m\u00e1s que una reacci\u00f3n de protecci\u00f3n del organismo para huir de las situaciones que percibe como peligrosas. Uno de los miedos m\u00e1s comunes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo superar el miedo a la oscuridad - Chupetes Personalizados - El blog de Tutete","og_description":"El miedo no es m\u00e1s que una reacci\u00f3n de protecci\u00f3n del organismo para huir de las situaciones que percibe como peligrosas. Uno de los miedos m\u00e1s comunes","og_url":"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/","og_site_name":"Chupetes Personalizados - El blog de Tutete","article_publisher":"https:\/\/www.facebook.com\/tutetecom\/","article_published_time":"2014-08-28T11:59:13+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/08\/miedo.jpg","type":"image\/jpeg"}],"author":"tutete","twitter_card":"summary_large_image","twitter_creator":"@Tutetecom","twitter_site":"@Tutetecom","twitter_misc":{"Written by":"tutete","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/#article","isPartOf":{"@id":"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/"},"author":{"name":"tutete","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf"},"headline":"C\u00f3mo superar el miedo a la oscuridad","datePublished":"2014-08-28T11:59:13+00:00","mainEntityOfPage":{"@id":"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/"},"wordCount":440,"commentCount":2,"image":{"@id":"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/#primaryimage"},"thumbnailUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/08\/miedo.jpg","keywords":["consejos beb\u00e9s"],"articleSection":["Recomendaciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/","url":"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/","name":"C\u00f3mo superar el miedo a la oscuridad - Chupetes Personalizados - El blog de Tutete","isPartOf":{"@id":"https:\/\/www.tutete.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/#primaryimage"},"image":{"@id":"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/#primaryimage"},"thumbnailUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/08\/miedo.jpg","datePublished":"2014-08-28T11:59:13+00:00","author":{"@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf"},"description":"El miedo no es m\u00e1s que una reacci\u00f3n de protecci\u00f3n del organismo para huir de las situaciones que percibe como peligrosas. Uno de los miedos m\u00e1s comunes","breadcrumb":{"@id":"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/#primaryimage","url":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/08\/miedo.jpg","contentUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/08\/miedo.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/tutete.com\/blog\/2014\/08\/miedo-oscuridad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.tutete.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Recomendaciones","item":"https:\/\/erp-pre.tutete.com\/blog\/recomendaciones\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo superar el miedo a la oscuridad"}]},{"@type":"WebSite","@id":"https:\/\/www.tutete.com\/blog\/#website","url":"https:\/\/www.tutete.com\/blog\/","name":"Chupetes Personalizados - El blog de Tutete","description":"Chupetes Personalizados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tutete.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf","name":"tutete","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g","caption":"tutete"},"url":"https:\/\/tutete.com\/blog\/author\/tutete\/"}]}},"_links":{"self":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/2733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/comments?post=2733"}],"version-history":[{"count":0,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/2733\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/media\/2734"}],"wp:attachment":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/media?parent=2733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/categories?post=2733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/tags?post=2733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}