{"id":2403,"date":"2014-02-28T13:24:37","date_gmt":"2014-02-28T13:24:37","guid":{"rendered":"http:\/\/chupetespersonalizados.com\/?p=2403"},"modified":"2014-02-28T13:24:37","modified_gmt":"2014-02-28T13:24:37","slug":"vista-bebes","status":"publish","type":"post","link":"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/","title":{"rendered":"La vista de mi beb\u00e9"},"content":{"rendered":"<p>Aunque los beb\u00e9s empiezan a desarrollar su vista a partir del sexto mes de la gestaci\u00f3n, <strong>en el momento de nacer, lo hacen con muy poca capacidad visual<\/strong>.<\/p>\n<p>Debemos tener en cuenta que han vivido durante mucho tiempo en un ambiente muy oscuro, por lo que las luces fuertes le deslumbran: hay que evitarlas, como la luz del flash de una c\u00e1mara de fotos, etc. Al principio los beb\u00e9s <strong>solamente pueden ver a una distancia de unos 25 cm.<\/strong> A m\u00e1s distancia no consigue enfocar correctamente y ve borroso.<!--more--><\/p>\n<p>Seguro que has notado alguna vez que el beb\u00e9 bizquea un poquito, esto es normal y ocurre porque todav\u00eda no consigue coordinar bien los ojos. Mientras no sea algo constante no debemos preocuparnos.<\/p>\n<p>Cuando nacen los beb\u00e9s <strong>solo ven en blanco y negro y no distinguen los colores<\/strong>, pero los contrastes les llaman mucho la atenci\u00f3n. Y tambi\u00e9n les atraen todos los movimientos que hay a su alrededor.<\/p>\n<p>Si quieres profundizar un poquito m\u00e1s sobre este tema, puedes ver este v\u00eddeo en el que nos explican muy bien c\u00f3mo se desarrolla la vista de nuestro beb\u00e9:<\/p>\n<p><iframe loading=\"lazy\" title=\"a.- Visi\u00f3n y reconocimiento de caras en bebes\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/1-kHF370TuY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><strong>\u00bfQu\u00e9 te ha parecido este video sobre la vista de los beb\u00e9s?\u00bfSab\u00edas ya como va a evolucionar la vista de tu peque?<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque los beb\u00e9s empiezan a desarrollar su vista a partir del sexto mes de la gestaci\u00f3n, en el momento de nacer, lo hacen con muy poca capacidad visual. Debemos tener en cuenta que han vivido durante mucho tiempo en un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[371],"tags":[493],"class_list":["post-2403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-infantil","tag-salud"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La vista de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete<\/title>\n<meta name=\"description\" content=\"Aunque los beb\u00e9s empiezan a desarrollar su vista a partir del sexto mes de la gestaci\u00f3n, en el momento de nacer, lo hacen con muy poca capacidad visual.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La vista de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"og:description\" content=\"Aunque los beb\u00e9s empiezan a desarrollar su vista a partir del sexto mes de la gestaci\u00f3n, en el momento de nacer, lo hacen con muy poca capacidad visual.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/\" \/>\n<meta property=\"og:site_name\" content=\"Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tutetecom\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-28T13:24:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/02\/vista.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"692\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"tutete\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:site\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"tutete\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/\"},\"author\":{\"name\":\"tutete\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\"},\"headline\":\"La vista de mi beb\u00e9\",\"datePublished\":\"2014-02-28T13:24:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/\"},\"wordCount\":234,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/02\/vista.jpg\",\"keywords\":[\"salud\"],\"articleSection\":[\"Salud infantil\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/\",\"url\":\"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/\",\"name\":\"La vista de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete\",\"isPartOf\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/02\/vista.jpg\",\"datePublished\":\"2014-02-28T13:24:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\"},\"description\":\"Aunque los beb\u00e9s empiezan a desarrollar su vista a partir del sexto mes de la gestaci\u00f3n, en el momento de nacer, lo hacen con muy poca capacidad visual.\",\"breadcrumb\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/#primaryimage\",\"url\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/02\/vista.jpg\",\"contentUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/02\/vista.jpg\",\"width\":1000,\"height\":692},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.tutete.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salud infantil\",\"item\":\"https:\/\/dev.tutete.com\/blog\/salud-infantil\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La vista de mi beb\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\",\"url\":\"https:\/\/www.tutete.com\/blog\/\",\"name\":\"Chupetes Personalizados - El blog de Tutete\",\"description\":\"Chupetes Personalizados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tutete.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\",\"name\":\"tutete\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g\",\"caption\":\"tutete\"},\"url\":\"https:\/\/tutete.com\/blog\/author\/tutete\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La vista de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete","description":"Aunque los beb\u00e9s empiezan a desarrollar su vista a partir del sexto mes de la gestaci\u00f3n, en el momento de nacer, lo hacen con muy poca capacidad visual.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/","og_locale":"es_ES","og_type":"article","og_title":"La vista de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete","og_description":"Aunque los beb\u00e9s empiezan a desarrollar su vista a partir del sexto mes de la gestaci\u00f3n, en el momento de nacer, lo hacen con muy poca capacidad visual.","og_url":"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/","og_site_name":"Chupetes Personalizados - El blog de Tutete","article_publisher":"https:\/\/www.facebook.com\/tutetecom\/","article_published_time":"2014-02-28T13:24:37+00:00","og_image":[{"width":1000,"height":692,"url":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/02\/vista.jpg","type":"image\/jpeg"}],"author":"tutete","twitter_card":"summary_large_image","twitter_creator":"@Tutetecom","twitter_site":"@Tutetecom","twitter_misc":{"Written by":"tutete","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/#article","isPartOf":{"@id":"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/"},"author":{"name":"tutete","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf"},"headline":"La vista de mi beb\u00e9","datePublished":"2014-02-28T13:24:37+00:00","mainEntityOfPage":{"@id":"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/"},"wordCount":234,"commentCount":0,"image":{"@id":"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/#primaryimage"},"thumbnailUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/02\/vista.jpg","keywords":["salud"],"articleSection":["Salud infantil"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/","url":"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/","name":"La vista de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete","isPartOf":{"@id":"https:\/\/www.tutete.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/#primaryimage"},"image":{"@id":"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/#primaryimage"},"thumbnailUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/02\/vista.jpg","datePublished":"2014-02-28T13:24:37+00:00","author":{"@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf"},"description":"Aunque los beb\u00e9s empiezan a desarrollar su vista a partir del sexto mes de la gestaci\u00f3n, en el momento de nacer, lo hacen con muy poca capacidad visual.","breadcrumb":{"@id":"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/#primaryimage","url":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/02\/vista.jpg","contentUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/02\/vista.jpg","width":1000,"height":692},{"@type":"BreadcrumbList","@id":"https:\/\/tutete.com\/blog\/2014\/02\/vista-bebes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.tutete.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Salud infantil","item":"https:\/\/dev.tutete.com\/blog\/salud-infantil\/"},{"@type":"ListItem","position":3,"name":"La vista de mi beb\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.tutete.com\/blog\/#website","url":"https:\/\/www.tutete.com\/blog\/","name":"Chupetes Personalizados - El blog de Tutete","description":"Chupetes Personalizados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tutete.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf","name":"tutete","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g","caption":"tutete"},"url":"https:\/\/tutete.com\/blog\/author\/tutete\/"}]}},"_links":{"self":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/2403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/comments?post=2403"}],"version-history":[{"count":0,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/2403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/media\/2404"}],"wp:attachment":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/media?parent=2403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/categories?post=2403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/tags?post=2403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}