{"id":2251,"date":"2014-01-27T15:00:48","date_gmt":"2014-01-27T15:00:48","guid":{"rendered":"http:\/\/chupetespersonalizados.com\/?p=2251"},"modified":"2014-01-27T15:00:48","modified_gmt":"2014-01-27T15:00:48","slug":"como-calmar-llanto-bebe","status":"publish","type":"post","link":"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/","title":{"rendered":"C\u00f3mo calmar el llanto de mi beb\u00e9"},"content":{"rendered":"<p>Lo cierto es que una de las cuestiones m\u00e1s complejas de los beb\u00e9s es <strong>conseguir conocerles hasta el punto de comprenderles y saber qu\u00e9 necesitan en cada momento<\/strong>, qu\u00e9 piden, qu\u00e9 quieren expresar, entre otras cuestiones.<\/p>\n<p>Esto se logra con el tiempo, <strong>terminamos sabiendo exactamente qu\u00e9 dicen en cada momento con solo un gesto<\/strong>, es cuesti\u00f3n de sumar experiencias similares, repetidas en el tiempo. <!--more--><\/p>\n<p><strong>Por qu\u00e9 llora un ni\u00f1o<\/strong><\/p>\n<p>La clave principal del llanto del ni\u00f1o es <strong>saber diferenciar entre llanto y quejido<\/strong>. No es lo mismo y \u00e9ste debe ser el primer paso.<\/p>\n<p>Al principio es esencial conocer al peque y diferenciar completamente uno de otro: el llanto normal vs llanto patol\u00f3gico.<\/p>\n<p><strong>Razones principales por las que lloran los beb\u00e9s<\/strong><\/p>\n<ol>\n<li>Hambre<\/li>\n<li>Necesidad de cambio: est\u00e1n sucios<\/li>\n<li>Reclaman atenci\u00f3n<\/li>\n<\/ol>\n<p>Adem\u00e1s, los ni\u00f1os lloran porque es su forma de expresi\u00f3n, o bien porque est\u00e1n enfermos. El llanto puede ser de ambos tipos y hay que saber reconocerlo para acertar a la hora de actuar.<br \/>\nOtros <a href=\"http:\/\/chupetespersonalizados.com\/2013\/08\/por-que-llora-mi-bebe\/\">nueve motivos por los que lloran los beb\u00e9s<\/a>.<\/p>\n<p><strong>Qu\u00e9 hacer si llora<\/strong><\/p>\n<ol>\n<li>Mantener la calma. Pase lo que pase.<\/li>\n<li>Primero debemos saber por qu\u00e9 llora y luego actuar en consecuencia.<\/li>\n<li>El llanto del beb\u00e9 el 100% de las veces requiere atenciones extra.<\/li>\n<li>Envuelve bien al beb\u00e9. La <a href=\"http:\/\/chupetespersonalizados.com\/2013\/09\/tecnica-swaddling-baby-wrapping\/\">t\u00e9cnica del Swaddling o baby wrapping<\/a> puede ayudar en la mayor\u00eda de los casos.<\/li>\n<li>El <a href=\"http:\/\/chupetespersonalizados.com\/2013\/08\/el-ruido-blanco\/\">ruido blanco<\/a>.<\/li>\n<li>El contacto <a href=\"http:\/\/chupetespersonalizados.com\/2013\/09\/el-contacto-piel-con-piel-es-esencial-2\/\">piel con piel<\/a>.<\/li>\n<li><strong>Balanceo<\/strong> para recrear su forma de estar en tu vientre.<\/li>\n<li>La sencilla <a href=\"http:\/\/chupetespersonalizados.com\/2013\/08\/fomentar-la-succion-saludable-y-los-chupetes-dinamicos-lovi\/\">succi\u00f3n<\/a>. Pecho, biber\u00f3n, chupetes, etc.<\/li>\n<li><strong>Los paseos<\/strong>. Las escaleras, paseos en coche. Cada beb\u00e9 es un mundo, con sus preferencias.<\/li>\n<li><strong>La m\u00fasica<\/strong>. No toda, pero cierta m\u00fasica ayuda.<\/li>\n<li>Juguetes o alguna forma de entretenimiento para distraerles de su llanto.<\/li>\n<li>Masajes suaves. Todo lo que sea contacto calma y beneficia.<\/li>\n<\/ol>\n<p>Si todo falla, tambi\u00e9n existen los milagros, como este anuncio japon\u00e9s muy curioso: <a href=\"http:\/\/www.japonpop.com\/2012\/10\/el-anuncio-que-hace-que-el-962-de-los-bebes-dejen-de-llorar\/\">el anuncio que calma el llanto de los beb\u00e9s<\/a>, instant\u00e1neamente, adem\u00e1s. Por probar que no quede \ud83d\ude09<\/p>\n<p><object id=\"flashObj\" width=\"640\" height=\"360\" classid=\"clsid:D27CDB6E-AE6D-11cf-96B8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=9,0,47,0\"><param name=\"movie\" value=\"http:\/\/c.brightcove.com\/services\/viewer\/federated_f9?isVid=1&#038;isUI=1\" \/><param name=\"bgcolor\" value=\"#FFFFFF\" \/><param name=\"flashVars\" value=\"web=externos&#038;videoId=1989279297001&#038;playerID=86420195001&#038;playerKey=AQ%2E%2E,AAAADP7KBSE%2E,NP37tnwPKWHJKQRgZyNX5lcPWsrTmeMq&#038;domain=embed&#038;dynamicStreaming=true\" \/><param name=\"base\" value=\"http:\/\/admin.brightcove.com\" \/><param name=\"wmode\" value=\"transparent\" \/><param name=\"seamlesstabbing\" value=\"false\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"swLiveConnect\" value=\"true\" \/><param name=\"allowScriptAccess\" value=\"always\" \/><embed src=\"http:\/\/c.brightcove.com\/services\/viewer\/federated_f9?isVid=1&#038;isUI=1\" wmode=\"transparent\" bgcolor=\"#FFFFFF\" flashVars=\"web=externos&#038;videoId=1989279297001&#038;playerID=86420195001&#038;playerKey=AQ%2E%2E,AAAADP7KBSE%2E,NP37tnwPKWHJKQRgZyNX5lcPWsrTmeMq&#038;domain=embed&#038;dynamicStreaming=true\" base=\"http:\/\/admin.brightcove.com\" name=\"flashObj\" width=\"640\" height=\"360\" seamlesstabbing=\"false\" type=\"application\/x-shockwave-flash\" allowFullScreen=\"true\" allowScriptAccess=\"always\" swLiveConnect=\"true\" pluginspage=\"http:\/\/www.macromedia.com\/shockwave\/download\/index.cgi?P1_Prod_Version=ShockwaveFlash\"><\/embed><\/object><\/p>\n<p>\u00bfLo hab\u00e9is probado? \ud83d\ude00 \u00bfC\u00f3mo llev\u00e1is el llanto de vuestro beb\u00e9? \u00bfSab\u00e9is qu\u00e9 quiere comunicar en cada caso? \u00bfTrucos? \ud83d\ude42<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo cierto es que una de las cuestiones m\u00e1s complejas de los beb\u00e9s es conseguir conocerles hasta el punto de comprenderles y saber qu\u00e9 necesitan en cada momento, qu\u00e9 piden, qu\u00e9 quieren expresar, entre otras cuestiones. Esto se logra con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2252,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[545],"tags":[],"class_list":["post-2251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recomendaciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo calmar el llanto de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete<\/title>\n<meta name=\"description\" content=\"Lo cierto es que una de las cuestiones m\u00e1s complejas de los beb\u00e9s es conseguir conocerles hasta el punto de comprenderles y saber qu\u00e9 necesitan en cada\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo calmar el llanto de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"og:description\" content=\"Lo cierto es que una de las cuestiones m\u00e1s complejas de los beb\u00e9s es conseguir conocerles hasta el punto de comprenderles y saber qu\u00e9 necesitan en cada\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/\" \/>\n<meta property=\"og:site_name\" content=\"Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tutetecom\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-27T15:00:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/bebe_llanto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"tutete\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:site\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"tutete\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/\"},\"author\":{\"name\":\"tutete\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\"},\"headline\":\"C\u00f3mo calmar el llanto de mi beb\u00e9\",\"datePublished\":\"2014-01-27T15:00:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/\"},\"wordCount\":378,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/bebe_llanto.jpg\",\"articleSection\":[\"Recomendaciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/\",\"url\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/\",\"name\":\"C\u00f3mo calmar el llanto de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete\",\"isPartOf\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/bebe_llanto.jpg\",\"datePublished\":\"2014-01-27T15:00:48+00:00\",\"author\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\"},\"description\":\"Lo cierto es que una de las cuestiones m\u00e1s complejas de los beb\u00e9s es conseguir conocerles hasta el punto de comprenderles y saber qu\u00e9 necesitan en cada\",\"breadcrumb\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/#primaryimage\",\"url\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/bebe_llanto.jpg\",\"contentUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/bebe_llanto.jpg\",\"width\":700,\"height\":466},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.tutete.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recomendaciones\",\"item\":\"https:\/\/erp-pre.tutete.com\/blog\/recomendaciones\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo calmar el llanto de mi beb\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\",\"url\":\"https:\/\/www.tutete.com\/blog\/\",\"name\":\"Chupetes Personalizados - El blog de Tutete\",\"description\":\"Chupetes Personalizados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tutete.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\",\"name\":\"tutete\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g\",\"caption\":\"tutete\"},\"url\":\"https:\/\/tutete.com\/blog\/author\/tutete\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo calmar el llanto de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete","description":"Lo cierto es que una de las cuestiones m\u00e1s complejas de los beb\u00e9s es conseguir conocerles hasta el punto de comprenderles y saber qu\u00e9 necesitan en cada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo calmar el llanto de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete","og_description":"Lo cierto es que una de las cuestiones m\u00e1s complejas de los beb\u00e9s es conseguir conocerles hasta el punto de comprenderles y saber qu\u00e9 necesitan en cada","og_url":"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/","og_site_name":"Chupetes Personalizados - El blog de Tutete","article_publisher":"https:\/\/www.facebook.com\/tutetecom\/","article_published_time":"2014-01-27T15:00:48+00:00","og_image":[{"width":700,"height":466,"url":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/bebe_llanto.jpg","type":"image\/jpeg"}],"author":"tutete","twitter_card":"summary_large_image","twitter_creator":"@Tutetecom","twitter_site":"@Tutetecom","twitter_misc":{"Written by":"tutete","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/#article","isPartOf":{"@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/"},"author":{"name":"tutete","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf"},"headline":"C\u00f3mo calmar el llanto de mi beb\u00e9","datePublished":"2014-01-27T15:00:48+00:00","mainEntityOfPage":{"@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/"},"wordCount":378,"commentCount":0,"image":{"@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/#primaryimage"},"thumbnailUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/bebe_llanto.jpg","articleSection":["Recomendaciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/","url":"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/","name":"C\u00f3mo calmar el llanto de mi beb\u00e9 - Chupetes Personalizados - El blog de Tutete","isPartOf":{"@id":"https:\/\/www.tutete.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/#primaryimage"},"image":{"@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/#primaryimage"},"thumbnailUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/bebe_llanto.jpg","datePublished":"2014-01-27T15:00:48+00:00","author":{"@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf"},"description":"Lo cierto es que una de las cuestiones m\u00e1s complejas de los beb\u00e9s es conseguir conocerles hasta el punto de comprenderles y saber qu\u00e9 necesitan en cada","breadcrumb":{"@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/#primaryimage","url":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/bebe_llanto.jpg","contentUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/bebe_llanto.jpg","width":700,"height":466},{"@type":"BreadcrumbList","@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-calmar-llanto-bebe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.tutete.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Recomendaciones","item":"https:\/\/erp-pre.tutete.com\/blog\/recomendaciones\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo calmar el llanto de mi beb\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.tutete.com\/blog\/#website","url":"https:\/\/www.tutete.com\/blog\/","name":"Chupetes Personalizados - El blog de Tutete","description":"Chupetes Personalizados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tutete.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf","name":"tutete","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g","caption":"tutete"},"url":"https:\/\/tutete.com\/blog\/author\/tutete\/"}]}},"_links":{"self":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/2251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/comments?post=2251"}],"version-history":[{"count":0,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/2251\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/media\/2252"}],"wp:attachment":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/media?parent=2251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/categories?post=2251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/tags?post=2251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}