{"id":2199,"date":"2014-01-20T14:24:35","date_gmt":"2014-01-20T14:24:35","guid":{"rendered":"http:\/\/chupetespersonalizados.com\/?p=2199"},"modified":"2014-01-20T14:24:35","modified_gmt":"2014-01-20T14:24:35","slug":"como-quitar-el-panal-ninos","status":"publish","type":"post","link":"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/","title":{"rendered":"C\u00f3mo quitar el pa\u00f1al a los ni\u00f1os"},"content":{"rendered":"<p>Una de las <strong>etapas m\u00e1s dif\u00edciles en el desarrollo de los ni\u00f1os<\/strong> es el momento de <strong>quitarse el pa\u00f1al<\/strong>, y comenzar a ir al ba\u00f1o solitos. Algunos ni\u00f1os est\u00e1n listos para empezar con este proceso a los 18 meses, pero hay otros que necesitan mucho m\u00e1s tiempo. <!--more--><\/p>\n<p>El control de esf\u00ednteres no es algo que los ni\u00f1os aprendan como a leer, escribir o montar en bici. <strong>Es todo un proceso que requiere de tiempo, paciencia y dedicaci\u00f3n.<\/strong> <\/p>\n<p>Adem\u00e1s, es <strong>una conquista que se adquiere de forma natural<\/strong> cuando el ni\u00f1o se encuentra totalmente preparado. No olvides que aprender a ir al ba\u00f1o sin pa\u00f1al <strong>no es una cuesti\u00f3n de voluntad, sino de capacidad<\/strong> por lo que no debemos enfadarnos si en las primeras semanas no obtenemos los resultados esperados.<\/p>\n<h3> \u00bfCu\u00e1ndo es el momento adecuado?<\/h3>\n<p>Normalmente <strong>los ni\u00f1os dan se\u00f1ales de que ya est\u00e1n preparados para comenzar a retirar el pa\u00f1al<\/strong>, s\u00f3lo hay que estar atento y observar mucho las conductas de los ni\u00f1os. Algunas de las actitudes m\u00e1s comunes entre los peques para indicarnos que ya est\u00e1n listos para este proceso son:<\/p>\n<ul>\n<li>Mantiene el pa\u00f1al seco durante m\u00e1s tiempo.<\/li>\n<li>Se queja cuando tiene el pa\u00f1al mojado.<\/li>\n<li>Comienza a avisar de que tiene ganas de hacer pip\u00ed.<\/li>\n<li>Se mueve mucho o \u00abse aguanta\u00bb las ganas de ir al ba\u00f1o.<\/li>\n<li>Muestra inter\u00e9s o imita a sus hermanitos cuando van al ba\u00f1o.<\/li>\n<\/ul>\n<h3>Consejos para quitar el pa\u00f1al<\/h3>\n<ol>\n<li><strong>S\u00e9 constante<\/strong>, si has decidido que es el momento, no recaigas y vuelvas a poner el pa\u00f1al a tu peque\u00f1o. <\/li>\n<li><strong>Expl\u00edcale que comienza una nueva etapa<\/strong> en la que s\u00f3lo utilizar\u00e1 el pa\u00f1al por las noches y deber\u00e1 ir al ba\u00f1o o utilizar un orinal cuando tenga ganas de ir al ba\u00f1o.<\/li>\n<li><strong>Pide a tu peque\u00f1o que te ayude a elegir su orinal<\/strong>. Cuando lo lleves a casa, puedes escribir en \u00e9l su nombre y dejar que lo pinte y que juegue con el.<\/li>\n<li><strong>Haz que se siente en su orinal una vez al d\u00eda<\/strong>, despu\u00e9s de desayunar, antes de ba\u00f1arse o cuando normalmente suele ir al ba\u00f1o. As\u00ed se ir\u00e1 acostumbrando al orinal y empezar\u00e1 a aceptarlo como parte de su rutina diaria.<\/li>\n<li><strong>Invita a tu peque a que vaya al ba\u00f1o con sus hermanos o contigo<\/strong>, pues los ni\u00f1os aprenden muchos de sus h\u00e1bitos por imitaci\u00f3n.<\/li>\n<li><strong>Pon el orinal en un lugar accesible<\/strong>. Como es port\u00e1til, puedes llevarlo al ba\u00f1o o al cuarto de juegos.<\/li>\n<li><strong>Felicita al ni\u00f1o cada vez que utilice su orinal<\/strong>. Puedes informar al resto de la familia o hacerle un peque\u00f1o regalo.<\/li>\n<\/ol>\n<p>No olvides que para quitar el pa\u00f1al a tu peque\u00f1o necesitar\u00e1s una buena dosis de <strong>dedicaci\u00f3n y paciencia<\/strong>, pero al final seguro que tu peque consigue ir al ba\u00f1o solito. <strong>\u00bfConoces alg\u00fan otro consejito para quitar el pa\u00f1al a los ni\u00f1os?<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una de las etapas m\u00e1s dif\u00edciles en el desarrollo de los ni\u00f1os es el momento de quitarse el pa\u00f1al, y comenzar a ir al ba\u00f1o solitos. Algunos ni\u00f1os est\u00e1n listos para empezar con este proceso a los 18 meses, pero [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[545],"tags":[437],"class_list":["post-2199","post","type-post","status-publish","format-standard","hentry","category-recomendaciones","tag-consejos-bebes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo quitar el pa\u00f1al a los ni\u00f1os - Chupetes Personalizados - El blog de Tutete<\/title>\n<meta name=\"description\" content=\"Una de las etapas m\u00e1s dif\u00edciles en el desarrollo de los ni\u00f1os es el momento de quitarse el pa\u00f1al, y comenzar a ir al ba\u00f1o solitos. Algunos ni\u00f1os est\u00e1n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo quitar el pa\u00f1al a los ni\u00f1os - Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"og:description\" content=\"Una de las etapas m\u00e1s dif\u00edciles en el desarrollo de los ni\u00f1os es el momento de quitarse el pa\u00f1al, y comenzar a ir al ba\u00f1o solitos. Algunos ni\u00f1os est\u00e1n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/\" \/>\n<meta property=\"og:site_name\" content=\"Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tutetecom\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-20T14:24:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2017\/05\/imagen_blog_nuevo_logo-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1029\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"tutete\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:site\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"tutete\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/\"},\"author\":{\"name\":\"tutete\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\"},\"headline\":\"C\u00f3mo quitar el pa\u00f1al a los ni\u00f1os\",\"datePublished\":\"2014-01-20T14:24:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/\"},\"wordCount\":532,\"commentCount\":0,\"keywords\":[\"consejos beb\u00e9s\"],\"articleSection\":[\"Recomendaciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/\",\"url\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/\",\"name\":\"C\u00f3mo quitar el pa\u00f1al a los ni\u00f1os - Chupetes Personalizados - El blog de Tutete\",\"isPartOf\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\"},\"datePublished\":\"2014-01-20T14:24:35+00:00\",\"author\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\"},\"description\":\"Una de las etapas m\u00e1s dif\u00edciles en el desarrollo de los ni\u00f1os es el momento de quitarse el pa\u00f1al, y comenzar a ir al ba\u00f1o solitos. Algunos ni\u00f1os est\u00e1n\",\"breadcrumb\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.tutete.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recomendaciones\",\"item\":\"https:\/\/erp-pre.tutete.com\/blog\/recomendaciones\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo quitar el pa\u00f1al a los ni\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\",\"url\":\"https:\/\/www.tutete.com\/blog\/\",\"name\":\"Chupetes Personalizados - El blog de Tutete\",\"description\":\"Chupetes Personalizados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tutete.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\",\"name\":\"tutete\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g\",\"caption\":\"tutete\"},\"url\":\"https:\/\/tutete.com\/blog\/author\/tutete\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo quitar el pa\u00f1al a los ni\u00f1os - Chupetes Personalizados - El blog de Tutete","description":"Una de las etapas m\u00e1s dif\u00edciles en el desarrollo de los ni\u00f1os es el momento de quitarse el pa\u00f1al, y comenzar a ir al ba\u00f1o solitos. Algunos ni\u00f1os est\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo quitar el pa\u00f1al a los ni\u00f1os - Chupetes Personalizados - El blog de Tutete","og_description":"Una de las etapas m\u00e1s dif\u00edciles en el desarrollo de los ni\u00f1os es el momento de quitarse el pa\u00f1al, y comenzar a ir al ba\u00f1o solitos. Algunos ni\u00f1os est\u00e1n","og_url":"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/","og_site_name":"Chupetes Personalizados - El blog de Tutete","article_publisher":"https:\/\/www.facebook.com\/tutetecom\/","article_published_time":"2014-01-20T14:24:35+00:00","og_image":[{"width":1029,"height":466,"url":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2017\/05\/imagen_blog_nuevo_logo-1.png","type":"image\/png"}],"author":"tutete","twitter_card":"summary_large_image","twitter_creator":"@Tutetecom","twitter_site":"@Tutetecom","twitter_misc":{"Written by":"tutete","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/#article","isPartOf":{"@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/"},"author":{"name":"tutete","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf"},"headline":"C\u00f3mo quitar el pa\u00f1al a los ni\u00f1os","datePublished":"2014-01-20T14:24:35+00:00","mainEntityOfPage":{"@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/"},"wordCount":532,"commentCount":0,"keywords":["consejos beb\u00e9s"],"articleSection":["Recomendaciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/","url":"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/","name":"C\u00f3mo quitar el pa\u00f1al a los ni\u00f1os - Chupetes Personalizados - El blog de Tutete","isPartOf":{"@id":"https:\/\/www.tutete.com\/blog\/#website"},"datePublished":"2014-01-20T14:24:35+00:00","author":{"@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf"},"description":"Una de las etapas m\u00e1s dif\u00edciles en el desarrollo de los ni\u00f1os es el momento de quitarse el pa\u00f1al, y comenzar a ir al ba\u00f1o solitos. Algunos ni\u00f1os est\u00e1n","breadcrumb":{"@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-quitar-el-panal-ninos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.tutete.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Recomendaciones","item":"https:\/\/erp-pre.tutete.com\/blog\/recomendaciones\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo quitar el pa\u00f1al a los ni\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/www.tutete.com\/blog\/#website","url":"https:\/\/www.tutete.com\/blog\/","name":"Chupetes Personalizados - El blog de Tutete","description":"Chupetes Personalizados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tutete.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf","name":"tutete","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g","caption":"tutete"},"url":"https:\/\/tutete.com\/blog\/author\/tutete\/"}]}},"_links":{"self":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/2199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/comments?post=2199"}],"version-history":[{"count":0,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/2199\/revisions"}],"wp:attachment":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/media?parent=2199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/categories?post=2199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/tags?post=2199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}