{"id":1620,"date":"2014-01-16T11:32:26","date_gmt":"2014-01-16T11:32:26","guid":{"rendered":"http:\/\/chupetespersonalizados.com\/?p=1620"},"modified":"2014-01-16T20:08:39","modified_gmt":"2014-01-16T20:08:39","slug":"como-estimular-autoconfianza-ninos","status":"publish","type":"post","link":"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/","title":{"rendered":"C\u00f3mo estimular la autoconfianza de tu peque"},"content":{"rendered":"<p>La sobreprotecci\u00f3n muchas veces se confunde con velar por la <strong>autoconfianza<\/strong> de tu peque. Debemos saber delimitar estos conceptos de modo que una cosa y otra no sean la misma.<\/p>\n<p>As\u00ed, separando claramente ambas cuestiones, hemos reunido pautas necesarias para estimular la autoconfianza de tu peque: <!--more--><\/p>\n<h3>Consejos para estimular y desarrollar la autoconfianza de tu beb\u00e9 sin caer en la sobreprotecci\u00f3n<\/h3>\n<ul>\n<li><strong>Cree en tu peque<\/strong>. Y que ella o \u00e9l lo sepa. Esto es lo primero. Si logras hacerles ver que crees en ellos ya tienes un gran primer paso en tu favor conseguido.<\/li>\n<li><strong>S\u00e9 su modelo a seguir<\/strong>. Al fin y al cabo, somos su ejemplo y siempre imitan a sus referentes por lo que ven d\u00eda a d\u00eda, si eres y, sobre todo, te muestras como una persona con autoconfianza, muy probablemente tu peque lo ser\u00e1 tambi\u00e9n.<\/li>\n<li><strong>Cada edad tiene sus momentos<\/strong>. Recuerda que aunque para ti siempre ser\u00e1 tu beb\u00e9, el beb\u00e9 crece, y deja de serlo, no lo olvides, sobre todo, saber hac\u00e9rselo ver.<\/li>\n<li><strong>Fomenta que se quieran mucho<\/strong>. Quererles es important\u00edsimo, pero ense\u00f1arles a que se quieran es clave: transmitirles lo mucho que valen siempre y nunca, pase lo que pase, les compares con otros. Ellos son \u00fanicos, excepcionales e irrepetibles, y as\u00ed deben aprenderlo a fuego.<\/li>\n<li><strong>Un espacio propio<\/strong>. Dejarles hacer. Que elijan ellos mismos lo que va a ser para ellos. Confiar en ellos es invertir en positivo, a la hora de construir personas con todos los elementos que le van a convertir en una persona adulta en positivo. Que est\u00e9n solos sin una supervisi\u00f3n 100% encima de ellos es muy enriquecedor para ellos.<\/li>\n<li><strong>Metas y retos<\/strong>. Insp\u00edrales para que se los pongan, para que los persigan cada d\u00eda. Lo mejor es que sean peque\u00f1os, a corto, medio o largo plazo, es imprescindible que resulten alcanzables para que asocien a esfuerzos y peque\u00f1os \u00e9xitos que van poco a poco sucedi\u00e9ndose sus retos diarios.<\/li>\n<li><strong>Cuida (mucho) lo que les dices<\/strong>. El lenguaje construye realidades, contruye realidades en tu favor en esta misi\u00f3n \ud83d\ude09<\/li>\n<\/ul>\n<p>\u00bfC\u00f3mo trabaj\u00e1is este tema en casa? \u00bfC\u00f3mo es tu peque en t\u00e9rminos de autoconfianza? \ud83d\ude42<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sobreprotecci\u00f3n muchas veces se confunde con velar por la autoconfianza de tu peque. Debemos saber delimitar estos conceptos de modo que una cosa y otra no sean la misma. As\u00ed, separando claramente ambas cuestiones, hemos reunido pautas necesarias para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2183,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[545],"tags":[],"class_list":["post-1620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recomendaciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo estimular la autoconfianza de tu peque - Chupetes Personalizados - El blog de Tutete<\/title>\n<meta name=\"description\" content=\"La sobreprotecci\u00f3n muchas veces se confunde con velar por la autoconfianza de tu peque. Debemos saber delimitar estos conceptos de modo que una cosa y\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo estimular la autoconfianza de tu peque - Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"og:description\" content=\"La sobreprotecci\u00f3n muchas veces se confunde con velar por la autoconfianza de tu peque. Debemos saber delimitar estos conceptos de modo que una cosa y\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/\" \/>\n<meta property=\"og:site_name\" content=\"Chupetes Personalizados - El blog de Tutete\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tutetecom\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-16T11:32:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-01-16T20:08:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/mama_bebe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"tutete\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:site\" content=\"@Tutetecom\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"tutete\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/\"},\"author\":{\"name\":\"tutete\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\"},\"headline\":\"C\u00f3mo estimular la autoconfianza de tu peque\",\"datePublished\":\"2014-01-16T11:32:26+00:00\",\"dateModified\":\"2014-01-16T20:08:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/\"},\"wordCount\":379,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/mama_bebe.jpg\",\"articleSection\":[\"Recomendaciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/\",\"url\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/\",\"name\":\"C\u00f3mo estimular la autoconfianza de tu peque - Chupetes Personalizados - El blog de Tutete\",\"isPartOf\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/mama_bebe.jpg\",\"datePublished\":\"2014-01-16T11:32:26+00:00\",\"dateModified\":\"2014-01-16T20:08:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\"},\"description\":\"La sobreprotecci\u00f3n muchas veces se confunde con velar por la autoconfianza de tu peque. Debemos saber delimitar estos conceptos de modo que una cosa y\",\"breadcrumb\":{\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/#primaryimage\",\"url\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/mama_bebe.jpg\",\"contentUrl\":\"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/mama_bebe.jpg\",\"width\":700,\"height\":467},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.tutete.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recomendaciones\",\"item\":\"https:\/\/erp-pre.tutete.com\/blog\/recomendaciones\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo estimular la autoconfianza de tu peque\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#website\",\"url\":\"https:\/\/www.tutete.com\/blog\/\",\"name\":\"Chupetes Personalizados - El blog de Tutete\",\"description\":\"Chupetes Personalizados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tutete.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf\",\"name\":\"tutete\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g\",\"caption\":\"tutete\"},\"url\":\"https:\/\/tutete.com\/blog\/author\/tutete\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo estimular la autoconfianza de tu peque - Chupetes Personalizados - El blog de Tutete","description":"La sobreprotecci\u00f3n muchas veces se confunde con velar por la autoconfianza de tu peque. Debemos saber delimitar estos conceptos de modo que una cosa y","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo estimular la autoconfianza de tu peque - Chupetes Personalizados - El blog de Tutete","og_description":"La sobreprotecci\u00f3n muchas veces se confunde con velar por la autoconfianza de tu peque. Debemos saber delimitar estos conceptos de modo que una cosa y","og_url":"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/","og_site_name":"Chupetes Personalizados - El blog de Tutete","article_publisher":"https:\/\/www.facebook.com\/tutetecom\/","article_published_time":"2014-01-16T11:32:26+00:00","article_modified_time":"2014-01-16T20:08:39+00:00","og_image":[{"width":700,"height":467,"url":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/mama_bebe.jpg","type":"image\/jpeg"}],"author":"tutete","twitter_card":"summary_large_image","twitter_creator":"@Tutetecom","twitter_site":"@Tutetecom","twitter_misc":{"Written by":"tutete","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/#article","isPartOf":{"@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/"},"author":{"name":"tutete","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf"},"headline":"C\u00f3mo estimular la autoconfianza de tu peque","datePublished":"2014-01-16T11:32:26+00:00","dateModified":"2014-01-16T20:08:39+00:00","mainEntityOfPage":{"@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/"},"wordCount":379,"commentCount":0,"image":{"@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/#primaryimage"},"thumbnailUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/mama_bebe.jpg","articleSection":["Recomendaciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/","url":"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/","name":"C\u00f3mo estimular la autoconfianza de tu peque - Chupetes Personalizados - El blog de Tutete","isPartOf":{"@id":"https:\/\/www.tutete.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/#primaryimage"},"image":{"@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/#primaryimage"},"thumbnailUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/mama_bebe.jpg","datePublished":"2014-01-16T11:32:26+00:00","dateModified":"2014-01-16T20:08:39+00:00","author":{"@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf"},"description":"La sobreprotecci\u00f3n muchas veces se confunde con velar por la autoconfianza de tu peque. Debemos saber delimitar estos conceptos de modo que una cosa y","breadcrumb":{"@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/#primaryimage","url":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/mama_bebe.jpg","contentUrl":"https:\/\/tutete.com\/blog\/wp-content\/uploads\/2014\/01\/mama_bebe.jpg","width":700,"height":467},{"@type":"BreadcrumbList","@id":"https:\/\/tutete.com\/blog\/2014\/01\/como-estimular-autoconfianza-ninos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.tutete.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Recomendaciones","item":"https:\/\/erp-pre.tutete.com\/blog\/recomendaciones\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo estimular la autoconfianza de tu peque"}]},{"@type":"WebSite","@id":"https:\/\/www.tutete.com\/blog\/#website","url":"https:\/\/www.tutete.com\/blog\/","name":"Chupetes Personalizados - El blog de Tutete","description":"Chupetes Personalizados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tutete.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/6d8747af72a579a778060dd5fc1ca8bf","name":"tutete","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tutete.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb6af56df141afb8af05e8ee9ed0a2d02eef46d2f007bab44db76b9758391a49?s=96&d=mm&r=g","caption":"tutete"},"url":"https:\/\/tutete.com\/blog\/author\/tutete\/"}]}},"_links":{"self":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/1620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/comments?post=1620"}],"version-history":[{"count":0,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/posts\/1620\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/media\/2183"}],"wp:attachment":[{"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/media?parent=1620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/categories?post=1620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tutete.com\/blog\/wp-json\/wp\/v2\/tags?post=1620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}